{"id":2550,"date":"2017-05-11T12:38:51","date_gmt":"2017-05-11T10:38:51","guid":{"rendered":"https:\/\/key-light.com\/?post_type=product&#038;p=2550"},"modified":"2024-03-14T16:13:26","modified_gmt":"2024-03-14T15:13:26","slug":"led-line-wall-washer","status":"publish","type":"product","link":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/","title":{"rendered":"Led Line Wall Washer"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A high quality recessed wall profile, made of aluminium. Ideal for lighting stairways, or alongside a wall in corridors. Light source not included (profile and cover only).<\/p>\n","protected":false},"featured_media":14638,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1357],"product_tag":[1180],"class_list":{"0":"post-2550","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-led-lines","7":"product_tag-led-line","8":"entry","9":"has-media","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-variable","16":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.10 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Led Line Wall Washer - Products - Keylight<\/title>\n<meta name=\"description\" content=\"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Led Line Wall Washer\" \/>\n<meta property=\"og:description\" content=\"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality\" \/>\n<meta property=\"og:url\" content=\"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/\" \/>\n<meta property=\"og:site_name\" content=\"Keylight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/keylightnl\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T15:13:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/key-light.com\/media\/keylight-led-line-wall-washer-alu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/\",\"url\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/\",\"name\":\"Led Line Wall Washer - Products - Keylight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/key-light.com\\\/media\\\/keylight-led-line-wall-washer-alu.jpg\",\"datePublished\":\"2017-05-11T10:38:51+00:00\",\"dateModified\":\"2024-03-14T15:13:26+00:00\",\"description\":\"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/key-light.com\\\/media\\\/keylight-led-line-wall-washer-alu.jpg\",\"contentUrl\":\"https:\\\/\\\/key-light.com\\\/media\\\/keylight-led-line-wall-washer-alu.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Keylight Led Line Wall Washer aluminium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/produit\\\/led-line-wall-washer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/key-light.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/key-light.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Led Line Wall Washer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/key-light.com\\\/fr\\\/\",\"name\":\"Keylight\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/key-light.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#organization\",\"name\":\"Keylight\",\"url\":\"https:\\\/\\\/key-light.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/key-light.com\\\/media\\\/keylight-logo-web-black.svg\",\"contentUrl\":\"https:\\\/\\\/key-light.com\\\/media\\\/keylight-logo-web-black.svg\",\"width\":230,\"height\":36,\"caption\":\"Keylight\"},\"image\":{\"@id\":\"https:\\\/\\\/key-light.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/keylightnl\",\"https:\\\/\\\/instagram.com\\\/keylightnl\",\"https:\\\/\\\/linkedin.com\\\/company\\\/keylightnl\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"0613.175.70.\u2206\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Led Line Wall Washer - Products - Keylight","description":"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/","og_locale":"fr_FR","og_type":"article","og_title":"Led Line Wall Washer","og_description":"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality","og_url":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/","og_site_name":"Keylight","article_publisher":"https:\/\/www.facebook.com\/keylightnl","article_modified_time":"2024-03-14T15:13:26+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/key-light.com\/media\/keylight-led-line-wall-washer-alu.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/","url":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/","name":"Led Line Wall Washer - Products - Keylight","isPartOf":{"@id":"https:\/\/key-light.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/#primaryimage"},"image":{"@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/#primaryimage"},"thumbnailUrl":"https:\/\/key-light.com\/media\/keylight-led-line-wall-washer-alu.jpg","datePublished":"2017-05-11T10:38:51+00:00","dateModified":"2024-03-14T15:13:26+00:00","description":"Discover the Led Line Wall Washer and other lighting products at Keylight \u2713 Large selection of Keylight design lighting \u2713 Quick delivery \u2713 High-end quality","breadcrumb":{"@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/#primaryimage","url":"https:\/\/key-light.com\/media\/keylight-led-line-wall-washer-alu.jpg","contentUrl":"https:\/\/key-light.com\/media\/keylight-led-line-wall-washer-alu.jpg","width":1200,"height":1200,"caption":"Keylight Led Line Wall Washer aluminium"},{"@type":"BreadcrumbList","@id":"https:\/\/key-light.com\/fr\/produit\/led-line-wall-washer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/key-light.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/key-light.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Led Line Wall Washer"}]},{"@type":"WebSite","@id":"https:\/\/key-light.com\/fr\/#website","url":"https:\/\/key-light.com\/fr\/","name":"Keylight","description":"","publisher":{"@id":"https:\/\/key-light.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/key-light.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/key-light.com\/fr\/#organization","name":"Keylight","url":"https:\/\/key-light.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/key-light.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/key-light.com\/media\/keylight-logo-web-black.svg","contentUrl":"https:\/\/key-light.com\/media\/keylight-logo-web-black.svg","width":230,"height":36,"caption":"Keylight"},"image":{"@id":"https:\/\/key-light.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/keylightnl","https:\/\/instagram.com\/keylightnl","https:\/\/linkedin.com\/company\/keylightnl"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"0613.175.70.\u2206","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/product\/2550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/media\/14638"}],"wp:attachment":[{"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/media?parent=2550"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/product_brand?post=2550"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2550"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/key-light.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}